{"id":16077,"date":"2025-02-14T20:25:02","date_gmt":"2025-02-14T19:25:02","guid":{"rendered":"https:\/\/fonspitius.org\/?p=16077"},"modified":"2025-02-17T20:55:39","modified_gmt":"2025-02-17T19:55:39","slug":"la-asamblea-del-fons-aprueba-el-plan-de-accion-y-el-presupuesto-de-2025","status":"publish","type":"post","link":"https:\/\/fonspitius.org\/es\/la-asamblea-del-fons-aprueba-el-plan-de-accion-y-el-presupuesto-de-2025\/","title":{"rendered":"La Asamblea del Fons aprueba el Plan de acci\u00f3n y el presupuesto de 2025"},"content":{"rendered":"<h3>La Asamblea del Fons aprueba el Plan de acci\u00f3n y el presupuesto de 2025<\/h3>\n<p>Eivissa, 14 de febrero de 2025.<\/p>\n<p>La asamblea del Fons se reuni\u00f3 ayer en la sede del Ayuntamiento de Eivissa y en esta primera reuni\u00f3n del a\u00f1o se aprob\u00f3 el Plan de acci\u00f3n y el presupuesto de 2025. Este presupuesto, que ser\u00e1 de 962.833\u20ac, se distribuir\u00e1 mayoritariamente entre las dos \u00e1reas de trabajo de la asociaci\u00f3n: la financiaci\u00f3n de proyectos de cooperaci\u00f3n y la educaci\u00f3n para la transformaci\u00f3n social.<\/p>\n<p>Asimismo, se aprobaron las bases de la convocatoria ordinaria de proyectos, con un plazo de presentaci\u00f3n del 15 de febrero al 15 de marzo, y las de la convocatoria de proyectos de emergencia, que est\u00e1 abierta desde principios de a\u00f1o y hasta el 30 de noviembre. Toda la documentaci\u00f3n est\u00e1 disponible en el apartado de convocatorias de esta misma web.<\/p>\n<p>Para conocer con m\u00e1s detalle el trabajo que se llevar\u00e1 a cabo durante todo el a\u00f1o, puede consultar el plan de acci\u00f3n aprobado a continuaci\u00f3n: <a href=\"https:\/\/fonspitius.org\/wp-content\/uploads\/PLA-DACCIO-2025.pdf\" target=\"_blank\" rel=\"noopener\">Plan de acci\u00f3n 2025<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Asamblea del Fons aprueba el Plan de acci\u00f3n y el presupuesto de 2025 Eivissa, 14 de febrero de 2025. La asamblea<\/p>\n","protected":false},"author":5,"featured_media":16073,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-16077","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"acf":[],"_links":{"self":[{"href":"https:\/\/fonspitius.org\/es\/wp-json\/wp\/v2\/posts\/16077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fonspitius.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fonspitius.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fonspitius.org\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/fonspitius.org\/es\/wp-json\/wp\/v2\/comments?post=16077"}],"version-history":[{"count":0,"href":"https:\/\/fonspitius.org\/es\/wp-json\/wp\/v2\/posts\/16077\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fonspitius.org\/es\/wp-json\/wp\/v2\/media\/16073"}],"wp:attachment":[{"href":"https:\/\/fonspitius.org\/es\/wp-json\/wp\/v2\/media?parent=16077"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fonspitius.org\/es\/wp-json\/wp\/v2\/categories?post=16077"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fonspitius.org\/es\/wp-json\/wp\/v2\/tags?post=16077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}